{"id":996,"date":"2014-04-20T12:01:23","date_gmt":"2014-04-20T12:01:23","guid":{"rendered":"http:\/\/mukom.mondragon.edu\/estudiar-informatica\/?p=996"},"modified":"2014-04-30T09:08:52","modified_gmt":"2014-04-30T09:08:52","slug":"acceso-a-la-universidad-desde-fp","status":"publish","type":"post","link":"https:\/\/mukom.mondragon.edu\/estudiar-informatica\/acceso-a-la-universidad-desde-fp\/","title":{"rendered":"Acceso a la Universidad desde FP"},"content":{"rendered":"<p style=\"text-align: justify\">Est\u00e1 claro que la finalidad de la <strong>Formaci\u00f3n Profesional (FP)<\/strong>\u00a0o los <strong>Ciclos Formativos de Grado Superior<\/strong> es formar profesionales que accedan directamente al mercado laboral. Pero adem\u00e1s, da la posibilidad de acceder a estudios universitarios en funci\u00f3n del Ciclo Formativo realizado.<\/p>\n<p style=\"text-align: justify\">En estos momentos las empresas requieren j\u00f3venes cualificados, y la ventaja de los j\u00f3venes que proceden de la FP est\u00e1 en haber cursado unos estudios orientados a la pr\u00e1ctica profesional.<\/p>\n<p style=\"text-align: justify\">Este es un motivo m\u00e1s por el que cada vez m\u00e1s alumnos, procedentes de FP, ampl\u00edan sus estudios y formaci\u00f3n con carreras universitarias. Y teniendo en cuenta c\u00f3mo est\u00e1 el mercado laboral, es una buena alternativa para una formaci\u00f3n cualificada de los alumnos.<\/p>\n<p style=\"text-align: justify\">El acceso a la universidad de este alumnado <strong>no requiere de prueba de acceso<\/strong>, aunque existe la posibilidad de realizar la parte espec\u00edfica de la Selectividad para subir la nota de acceso.<\/p>\n<p style=\"text-align: justify\">En estos \u00faltimos cursos, nuestros alumnos de FP del <strong>Ciclo de <a title=\"Ciclo Formativo en T\u00e9cnico Superior en Administraci\u00f3n de Sistemas Inform\u00e1ticos en Red\" href=\"http:\/\/www.mondragon.edu\/es\/eps\/estudios\/ciclos-formativos-de-grado-superior\/tecnico-superior-en-administracion-de-sistemas-informaticos\/tecnico-superior-en-administracion-de-sistemas-informaticos\">Administraci\u00f3n de Sistemas Inform\u00e1ticos en Red<\/a><\/strong> que han accedido a <a title=\"Mondragon Unibertsitatea\" href=\"http:\/\/www.mondragon.edu\/\">MU<\/a>, pese a las dificultades de superar ciertas asignaturas de ciencias (como C\u00e1lculo o F\u00edsica), han demostrado estar despu\u00e9s por encima de muchos de sus compa\u00f1eros provenientes de Bachiller. Y esto se debe al hecho de haber cursado durante dos a\u00f1os la FP y haber realizado las pr\u00e1cticas en la empresa. Este bagaje que poseen, hace que nuestros alumnos superen las asignaturas espec\u00edficas de las titulaciones de <a title=\"Grado en ingenier\u00eda en Inform\u00e1tica\" href=\"http:\/\/www.mondragon.edu\/es\/estudios\/grados\/grado-en-ingenieria-en-informatica\">Grado en Ingenier\u00eda en Inform\u00e1tica<\/a> y <a title=\"Grado en Ingenier\u00eda en Sistemas de Telecomunicaci\u00f3n\" href=\"http:\/\/www.mondragon.edu\/es\/estudios\/grados\/grado-en-ingenieria-en-sistemas-de-telecomunicacion\/\">Grado en Ingenier\u00eda en Sistemas de\u00a0Telecomunicaci\u00f3n<\/a> con una buena nota.<\/p>\n<p style=\"text-align: justify\">El modelo educativo de MU, hace posible que nuestros alumnos de FP, <strong>adquieran las competencias de una forma natural y sencilla<\/strong>. Y todo esto no empuja a recomendar a nuestros alumnos, que ampl\u00eden sus estudios y vengan a MU.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 claro que la finalidad de la Formaci\u00f3n Profesional (FP)\u00a0o los Ciclos Formativos de Grado Superior es formar profesionales que accedan directamente al mercado laboral. Pero adem\u00e1s, da la posibilidad de acceder a estudios universitarios en funci\u00f3n del Ciclo Formativo realizado. En estos momentos las empresas requieren j\u00f3venes cualificados, y la ventaja de los j\u00f3venes que proceden de la FP est\u00e1 en haber cursado unos estudios orientados a la pr\u00e1ctica profesional. Este es un motivo m\u00e1s por el que cada vez m\u00e1s alumnos, procedentes de FP, ampl\u00edan sus estudios y formaci\u00f3n con carreras universitarias. Y teniendo en cuenta c\u00f3mo est\u00e1 el mercado laboral, es una buena alternativa para una formaci\u00f3n cualificada de los alumnos. El acceso a la universidad de este alumnado no requiere de prueba de acceso, aunque existe la posibilidad de realizar la parte espec\u00edfica de la Selectividad..<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[38,4],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mukom.mondragon.edu\/estudiar-informatica\/wp-json\/wp\/v2\/posts\/996"}],"collection":[{"href":"https:\/\/mukom.mondragon.edu\/estudiar-informatica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mukom.mondragon.edu\/estudiar-informatica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/estudiar-informatica\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/estudiar-informatica\/wp-json\/wp\/v2\/comments?post=996"}],"version-history":[{"count":1,"href":"https:\/\/mukom.mondragon.edu\/estudiar-informatica\/wp-json\/wp\/v2\/posts\/996\/revisions"}],"predecessor-version":[{"id":997,"href":"https:\/\/mukom.mondragon.edu\/estudiar-informatica\/wp-json\/wp\/v2\/posts\/996\/revisions\/997"}],"wp:attachment":[{"href":"https:\/\/mukom.mondragon.edu\/estudiar-informatica\/wp-json\/wp\/v2\/media?parent=996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/estudiar-informatica\/wp-json\/wp\/v2\/categories?post=996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/estudiar-informatica\/wp-json\/wp\/v2\/tags?post=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}