{"id":1072,"date":"2013-11-01T11:08:17","date_gmt":"2013-11-01T10:08:17","guid":{"rendered":"http:\/\/blog-pertsonalak.mondragon.edu\/numbers\/?p=1072"},"modified":"2013-11-01T11:08:17","modified_gmt":"2013-11-01T10:08:17","slug":"6-arazoa-kromoekin-jolasten","status":"publish","type":"post","link":"https:\/\/mukom.mondragon.edu\/numbers\/2013\/11\/01\/6-arazoa-kromoekin-jolasten\/","title":{"rendered":"6.arazoa: kromoekin jolasten!"},"content":{"rendered":"<p style=\"text-align: justify\">Aitor y Eba est\u00e1n estudiando cuarto de primaria. Les gusta mucho jugar a cromos cuando salen de clase, de modo que un d\u00eda por la tarde antes de ir a casa tienen la siguiente conversaci\u00f3n:<\/p>\n<p style=\"text-align: justify\">&#8211; <strong>Aitor<\/strong>: Eba, \u00bfpor qu\u00e9 no me das tres de tus cromos? De este modo, tendremos el mismo n\u00famero de cromos.<\/p>\n<p style=\"text-align: justify\">A lo que Eba le contesta:<\/p>\n<p style=\"text-align: justify\">&#8211; <strong>Eba<\/strong>: Mejor dame tu dos cromos, as\u00ed \u00a0yo tendr\u00e9 el triple de cromos que tu.<\/p>\n<p style=\"text-align: justify\">\u00bfCu\u00e1ntos cromos ten\u00eda Eba y cu\u00e1ntos Aitor?<\/p>\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f147-o1\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/numbers\/wp-json\/wp\/v2\/posts\/1072#wpcf7-f147-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"147\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f147-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p>Tu nombre (requerido)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Tu Email (requerido)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Tu Mensaje<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"HOLA\"><label><span class=\"wpcf7-quiz-label\">Hitz gakoa \/ Palabra clave:<\/span> <input type=\"text\" name=\"HOLA\" size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_HOLA\" value=\"0bc6b841a28cde60d4a40baab6de8fad\" \/><\/span><\/p>\n<p><input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<p style=\"display: none !important;\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"3\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aitor y Eba est\u00e1n estudiando cuarto de primaria. Les gusta mucho jugar a cromos cuando salen de clase, de modo que un d\u00eda por la tarde antes de ir a casa tienen la siguiente conversaci\u00f3n: &#8211; Aitor: Eba, \u00bfpor qu\u00e9 no me das tres de tus cromos? De este modo, tendremos el mismo n\u00famero de cromos. A lo que Eba le contesta: &#8211; Eba: Mejor dame tu dos cromos, as\u00ed \u00a0yo tendr\u00e9 el triple de cromos que tu. \u00bfCu\u00e1ntos cromos ten\u00eda Eba y cu\u00e1ntos Aitor?<\/p>\n","protected":false},"author":265,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/1072"}],"collection":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/comments?post=1072"}],"version-history":[{"count":0,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/1072\/revisions"}],"wp:attachment":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/categories?post=1072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/tags?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}