{"id":1116,"date":"2013-11-15T10:02:22","date_gmt":"2013-11-15T09:02:22","guid":{"rendered":"http:\/\/blog-pertsonalak.mondragon.edu\/numbers\/?p=1116"},"modified":"2013-11-15T10:02:22","modified_gmt":"2013-11-15T09:02:22","slug":"matematikak-arriskuan","status":"publish","type":"post","link":"https:\/\/mukom.mondragon.edu\/numbers\/2013\/11\/15\/matematikak-arriskuan\/","title":{"rendered":"Matematikak arriskuan!"},"content":{"rendered":"<p style=\"text-align: justify\">\u00daltimamente no dejamos de o\u00edr un d\u00eda y otro tambi\u00e9n noticias sobre la reforma educativa, la ley LOMCE. Si alguna de las enmiendas a esta ley sale adelante, nos veremos con que los bachilleratos de ciencias sociales y humanidades se unifican; de este modo, lat\u00edn ser\u00e1 obligatorio en el nuevo bachillerato y matem\u00e1ticas pasa a ser una optativa; no entro en la pol\u00e9mica de si el lat\u00edn es o no es m\u00e1s importante que las matem\u00e1ticas, pero debido a esta unificaci\u00f3n puede darse el caso de que un alumno que vaya a cursar, por ejemplo, estudios de GADE no haya dado en bachillerato matem\u00e1ticas. \u00abNo pasa nada, lo estudiar\u00e1 en la universidad\u00bb piensan algunos&#8230;<\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/www.eldiario.es\/andalucia\/desdeelsur\/Divide-et-vinces_6_196040411.html\">Aqu\u00ed<\/a> ten\u00e9is una reflexi\u00f3n bastante interesante sobre todo esto; os animo a leerlo y luego a compartir un poco vuestra visi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00daltimamente no dejamos de o\u00edr un d\u00eda y otro tambi\u00e9n noticias sobre la reforma educativa, la ley LOMCE. Si alguna de las enmiendas a esta ley sale adelante, nos veremos con que los bachilleratos de ciencias sociales y humanidades se unifican; de este modo, lat\u00edn ser\u00e1 obligatorio en el nuevo bachillerato y matem\u00e1ticas pasa a ser una optativa; no entro en la pol\u00e9mica de si el lat\u00edn es o no es m\u00e1s importante que las matem\u00e1ticas, pero debido a esta unificaci\u00f3n puede darse el caso de que un alumno que vaya a cursar, por ejemplo, estudios de GADE no haya dado en bachillerato matem\u00e1ticas. \u00abNo pasa nada, lo estudiar\u00e1 en la universidad\u00bb piensan algunos&#8230; Aqu\u00ed ten\u00e9is una reflexi\u00f3n bastante interesante sobre todo esto; os animo a leerlo y luego a compartir un poco vuestra visi\u00f3n.<\/p>\n","protected":false},"author":265,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/1116"}],"collection":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/comments?post=1116"}],"version-history":[{"count":0,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/1116\/revisions"}],"wp:attachment":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/media?parent=1116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/categories?post=1116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/tags?post=1116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}