{"id":1487,"date":"2015-05-22T15:53:01","date_gmt":"2015-05-22T13:53:01","guid":{"rendered":"http:\/\/blog-pertsonalak.mondragon.edu\/numbers\/?p=1487"},"modified":"2015-05-22T15:53:01","modified_gmt":"2015-05-22T13:53:01","slug":"24-arazoa-bitxigileari-laguntzen","status":"publish","type":"post","link":"https:\/\/mukom.mondragon.edu\/numbers\/2015\/05\/22\/24-arazoa-bitxigileari-laguntzen\/","title":{"rendered":"24. arazoa: Bitxigileari laguntzen!"},"content":{"rendered":"<p style=\"text-align: justify\">Miren ha encontrado en la casa de su abuela una pulsera de oro, pero est\u00e1 rota en cuatro trozos. Cada trozo consta de tres eslabones. Le gusta mucho, por lo que lo lleva a una joyer\u00eda para que lo arreglen.<\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/blog-pertsonalak.mondragon.edu\/numbers\/files\/2015\/05\/24.arazoa.jpg\"><img loading=\"lazy\" class=\"aligncenter  wp-image-1489\" src=\"http:\/\/blog-pertsonalak.mondragon.edu\/numbers\/files\/2015\/05\/24.arazoa.jpg\" alt=\"24.arazoa\" width=\"120\" height=\"111\" \/><\/a>El joyero le hace el presupuesto del arreglo y le comenta que tiene que soldar cuatro eslabones: \u00abcomo soldar cada eslab\u00f3n cuesta 4 euros, el presupuesto total ser\u00eda de 16 euros\u00bb. \u00a0Pero Miren no est\u00e1 de acuerdo y le dice que se puede hacer soldando solo tres eslabones. \u00bfC\u00f3mo?<\/p>\n<p style=\"text-align: justify\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f867-o1\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/numbers\/wp-json\/wp\/v2\/posts\/1487#wpcf7-f867-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"867\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f867-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p>Tu nombre (requerido)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Tu Email (requerido)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Tu Mensaje<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"HOLA\"><label><span class=\"wpcf7-quiz-label\">Hitz gakoa \/ Palabra clave:<\/span> <input type=\"text\" name=\"HOLA\" size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_HOLA\" value=\"0bc6b841a28cde60d4a40baab6de8fad\" \/><\/span><\/p>\n<p><input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<p style=\"display: none !important;\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"139\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Miren ha encontrado en la casa de su abuela una pulsera de oro, pero est\u00e1 rota en cuatro trozos. Cada trozo consta de tres eslabones. Le gusta mucho, por lo que lo lleva a una joyer\u00eda para que lo arreglen. El joyero le hace el presupuesto del arreglo y le comenta que tiene que soldar cuatro eslabones: \u00abcomo soldar cada eslab\u00f3n cuesta 4 euros, el presupuesto total ser\u00eda de 16 euros\u00bb. \u00a0Pero Miren no est\u00e1 de acuerdo y le dice que se puede hacer soldando solo tres eslabones. \u00bfC\u00f3mo?<\/p>\n","protected":false},"author":265,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/1487"}],"collection":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/comments?post=1487"}],"version-history":[{"count":0,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/1487\/revisions"}],"wp:attachment":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/media?parent=1487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/categories?post=1487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/tags?post=1487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}