{"id":202,"date":"2012-09-28T15:16:28","date_gmt":"2012-09-28T13:16:28","guid":{"rendered":"http:\/\/blog-pertsonalak.mondragon.edu\/numbers\/?p=202"},"modified":"2012-09-28T15:16:28","modified_gmt":"2012-09-28T13:16:28","slug":"infinitua-maitasuna-edo-gorrotoa","status":"publish","type":"post","link":"https:\/\/mukom.mondragon.edu\/numbers\/2012\/09\/28\/infinitua-maitasuna-edo-gorrotoa\/","title":{"rendered":"Infinitua: maitasuna edo gorrotoa?"},"content":{"rendered":"<p>Estos d\u00edas en clase no hacemos otra cosa que ver el infinito por todas partes: a la hora de calcular \u00a0l\u00edmites, el infinito por s\u00ed solo no nos da ning\u00fan problema, pero si va acompa\u00f1ado de cero, de uno, u de otro infinito, s\u00ed que \u00a0podr\u00edamos encontrarnos ante \u00a0problemas: las temidas indeterminaciones.<\/p>\n<p>Cuando nos aparece por primera vez \u00a0el signo del infinito en la pizarra, empezamos preguntando: \u00bfy eso qu\u00e9 es?, \u00a0\u00bfc\u00f3mo se hace? \u00a0Y pronto viene la respuesta: Ah, ya s\u00e9! Es un ocho tumbado. \u00a0Pues NO!!! \u00a0Para que ve\u00e1is que no se trata de un ocho tumbado, sino que es una curva mucho m\u00e1s curiosa, pod\u00e9is mirar aqu\u00ed: la \u00a0<a href=\"http:\/\/gaussianos.com\/no-lo-llames-infinito-llamalo-lemniscata\/#more-8611\">lemniscata de Bernoulli<\/a>.<\/p>\n<p>\u00bfHab\u00e9is visto el pececito? \u00a0 \u00bfY el analema que podemos observar en la naturaleza?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estos d\u00edas en clase no hacemos otra cosa que ver el infinito por todas partes: a la hora de calcular \u00a0l\u00edmites, el infinito por s\u00ed solo no nos da ning\u00fan problema, pero si va acompa\u00f1ado de cero, de uno, u de otro infinito, s\u00ed que \u00a0podr\u00edamos encontrarnos ante \u00a0problemas: las temidas indeterminaciones. Cuando nos aparece por primera vez \u00a0el signo del infinito en la pizarra, empezamos preguntando: \u00bfy eso qu\u00e9 es?, \u00a0\u00bfc\u00f3mo se hace? \u00a0Y pronto viene la respuesta: Ah, ya s\u00e9! Es un ocho tumbado. \u00a0Pues NO!!! \u00a0Para que ve\u00e1is que no se trata de un ocho tumbado, sino que es una curva mucho m\u00e1s curiosa, pod\u00e9is mirar aqu\u00ed: la \u00a0lemniscata de Bernoulli. \u00bfHab\u00e9is visto el pececito? \u00a0 \u00bfY el analema que podemos observar en la naturaleza?<\/p>\n","protected":false},"author":265,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/202"}],"collection":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/comments?post=202"}],"version-history":[{"count":0,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/202\/revisions"}],"wp:attachment":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/media?parent=202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/categories?post=202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/tags?post=202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}