{"id":2092,"date":"2017-11-12T19:43:50","date_gmt":"2017-11-12T18:43:50","guid":{"rendered":"https:\/\/mukom.mondragon.edu\/numbers\/?p=2092"},"modified":"2017-11-12T21:08:39","modified_gmt":"2017-11-12T20:08:39","slug":"7-arazoa-altxorraren-bila","status":"publish","type":"post","link":"https:\/\/mukom.mondragon.edu\/numbers\/2017\/11\/12\/7-arazoa-altxorraren-bila\/","title":{"rendered":"7. arazoa: altxorraren bila!"},"content":{"rendered":"<div style=\"text-align: justify\">Mario P\u00e9rez era un famoso busca tesoros. Un buen d\u00eda se encontr\u00f3 con una caja que conten\u00eda un importante bot\u00edn, pero no hab\u00eda forma de abrirla. Entonces pudo ver una nota que dec\u00eda:\u00a0<i>La combinaci\u00f3n para abrir la caja es un n\u00famero de 4 d\u00edgitos. Como tendr\u00edas 10.000 combinaciones distintas y quiero que sea tu astucia la que abra el cofre, te proporciono las siguientes pistas:\u00a0<\/i><\/div>\n<div style=\"text-align: justify\"><\/div>\n<div><i>N\u00famero\u00a0 \u00a0 Perfecto\u00a0 \u00a0 Casi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <img loading=\"lazy\" class=\"wp-image-2096 alignright\" src=\"https:\/\/mukom.mondragon.edu\/numbers\/files\/2017\/11\/chest-1657362_1920-300x200.png\" alt=\"chest-1657362_1920\" width=\"459\" height=\"306\" srcset=\"https:\/\/mukom.mondragon.edu\/numbers\/files\/2017\/11\/chest-1657362_1920-300x200.png 300w, https:\/\/mukom.mondragon.edu\/numbers\/files\/2017\/11\/chest-1657362_1920-768x512.png 768w, https:\/\/mukom.mondragon.edu\/numbers\/files\/2017\/11\/chest-1657362_1920-1024x683.png 1024w, https:\/\/mukom.mondragon.edu\/numbers\/files\/2017\/11\/chest-1657362_1920-400x267.png 400w, https:\/\/mukom.mondragon.edu\/numbers\/files\/2017\/11\/chest-1657362_1920.png 1920w\" sizes=\"(max-width: 459px) 100vw, 459px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/i><\/div>\n<div><i>1974\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a02\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 0<\/i><\/div>\n<div><i>1920\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 1\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a01<\/i><\/div>\n<div><i>9607\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a00\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 2<\/i><\/div>\n<div><i>6045\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a00\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 1<\/i><\/div>\n<div style=\"text-align: justify\"><\/div>\n<div style=\"text-align: justify\"><\/div>\n<div style=\"text-align: justify\">En la columna\u00a0<i>N\u00famero\u00a0<\/i>puedes ver n\u00fameros de cuatro d\u00edgitos de las caracter\u00edsticas del que tienes que encontrar.<\/div>\n<div style=\"text-align: justify\">La columna\u00a0<i>Perfecto<\/i>\u00a0indica el n\u00famero de d\u00edgitos que forman parte del n\u00famero por descubrir y que est\u00e1n en su sitio.<\/div>\n<div style=\"text-align: justify\">La columna<i>\u00a0Casi\u00a0<\/i>indica el n\u00famero de d\u00edgitos que forman pare del n\u00famero secreto pero que no est\u00e1n en su justo lugar.<\/div>\n<div style=\"text-align: justify\">\u00bfTe atrever\u00edas a intentar ser\u00a0 t\u00fa quien abra la caja y acceda al tesoro encontrado, al menos, una combinaci\u00f3n v\u00e1lida?<\/div>\n<div>Gracias a Mar\u00eda por este acertijo.<\/div>\n<div><\/div>\n<div><b><\/b><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f148-o1\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/numbers\/wp-json\/wp\/v2\/posts\/2092#wpcf7-f148-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"148\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f148-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p>Tu nombre (requerido)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Tu Email (requerido)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Tu Mensaje<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"HOLA\"><label><span class=\"wpcf7-quiz-label\">Hitz gakoa \/ Palabra clave:<\/span> <input type=\"text\" name=\"HOLA\" size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_HOLA\" value=\"0bc6b841a28cde60d4a40baab6de8fad\" \/><\/span><\/p>\n<p><input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<p style=\"display: none !important;\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"23\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mario P\u00e9rez era un famoso busca tesoros. Un buen d\u00eda se encontr\u00f3 con una caja que conten\u00eda un importante bot\u00edn, pero no hab\u00eda forma de abrirla. Entonces pudo ver una nota que dec\u00eda:\u00a0La combinaci\u00f3n para abrir la caja es un n\u00famero de 4 d\u00edgitos. Como tendr\u00edas 10.000 combinaciones distintas y quiero que sea tu astucia la que abra el cofre, te proporciono las siguientes pistas:\u00a0 N\u00famero\u00a0 \u00a0 Perfecto\u00a0 \u00a0 Casi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 1974\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a02\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 0 1920\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 1\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a01 9607\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a00\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 2 6045\u00a0 \u00a0 \u00a0 \u00a0 \u00a0..<\/p>\n","protected":false},"author":265,"featured_media":-1,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/2092"}],"collection":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/comments?post=2092"}],"version-history":[{"count":8,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/2092\/revisions"}],"predecessor-version":[{"id":2101,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/2092\/revisions\/2101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/media?parent=2092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/categories?post=2092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/tags?post=2092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}