{"id":439,"date":"2012-11-09T10:04:55","date_gmt":"2012-11-09T09:04:55","guid":{"rendered":"http:\/\/blog-pertsonalak.mondragon.edu\/numbers\/?p=439"},"modified":"2012-11-09T10:04:55","modified_gmt":"2012-11-09T09:04:55","slug":"8-arazoa-konpratan","status":"publish","type":"post","link":"https:\/\/mukom.mondragon.edu\/numbers\/2012\/11\/09\/8-arazoa-konpratan\/","title":{"rendered":"8. arazoa: Konpratan!"},"content":{"rendered":"<p>Este verano Olaia y Saioa han ido de turismo \u00a0a Tailandia. Visitaron las distintas ciudades pintorescas, las maravillosas playas, &#8230; \u00a0Tambi\u00e9n quer\u00edan aprovechar para comprar distintos productos que all\u00ed se pueden encontrar m\u00e1s baratos. Entre estas cosas, estaba la c\u00e1mara de fotos que quer\u00eda Olaia. De este modo, estaban en una tienda donde un vendedor les estaba ense\u00f1ando varias c\u00e1maras, cuando una mujer compr\u00f3 una c\u00e1mara \u00a0de \u00a04782 Thai Bahts (unos 122 euros al cambio). Para pagarlo entreg\u00f3 un cheque de 7848 Thai Bahts (200 euros). Como el dependiente no ten\u00eda cambios en ese momento, envi\u00f3 a un compa\u00f1ero al restaurante de al lado para que cambiara. Cuando obtuvo el\u00a0dinero, dio a la mujer el cambio y le envolvi\u00f3 la c\u00e1mara que hab\u00eda adquirido. \u00a0Cinco minutos m\u00e1s tarde, lleg\u00f3 el due\u00f1o del restaurante \u00a0gritando que le devolviera el dinero ya que el cheque era falso. El vendedor le tuvo que devolver los 7848 Thai Bahts que le hab\u00eda cambiado. Olaia y Saioa viendo todo el jaleo abandonaron la tienda.<\/p>\n<p>Cuando las dos amigan recuerdan lo sucedido les surge una duda: \u00bfQu\u00e9 p\u00e9rdidas tuvo el vendedor con todo el negocio?<\/p>\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f149-o1\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/numbers\/wp-json\/wp\/v2\/posts\/439#wpcf7-f149-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"149\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f149-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p>Tu nombre (requerido)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Tu Email (requerido)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/p>\n<p>Tu Mensaje<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"HOLA\"><label><span class=\"wpcf7-quiz-label\">Hitz gakoa \/ Palabra clave:<\/span> <input type=\"text\" name=\"HOLA\" size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_HOLA\" value=\"0bc6b841a28cde60d4a40baab6de8fad\" \/><\/span><\/p>\n<p><input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<p style=\"display: none !important;\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"12\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este verano Olaia y Saioa han ido de turismo \u00a0a Tailandia. Visitaron las distintas ciudades pintorescas, las maravillosas playas, &#8230; \u00a0Tambi\u00e9n quer\u00edan aprovechar para comprar distintos productos que all\u00ed se pueden encontrar m\u00e1s baratos. Entre estas cosas, estaba la c\u00e1mara de fotos que quer\u00eda Olaia. De este modo, estaban en una tienda donde un vendedor les estaba ense\u00f1ando varias c\u00e1maras, cuando una mujer compr\u00f3 una c\u00e1mara \u00a0de \u00a04782 Thai Bahts (unos 122 euros al cambio). Para pagarlo entreg\u00f3 un cheque de 7848 Thai Bahts (200 euros). Como el dependiente no ten\u00eda cambios en ese momento, envi\u00f3 a un compa\u00f1ero al restaurante de al lado para que cambiara. Cuando obtuvo el\u00a0dinero, dio a la mujer el cambio y le envolvi\u00f3 la c\u00e1mara que hab\u00eda adquirido. \u00a0Cinco minutos m\u00e1s tarde, lleg\u00f3 el due\u00f1o del restaurante \u00a0gritando que le devolviera el dinero ya..<\/p>\n","protected":false},"author":265,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/439"}],"collection":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":0,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/439\/revisions"}],"wp:attachment":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/media?parent=439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/categories?post=439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/tags?post=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}