{"id":863,"date":"2013-04-19T13:22:50","date_gmt":"2013-04-19T11:22:50","guid":{"rendered":"http:\/\/blog-pertsonalak.mondragon.edu\/numbers\/?p=863"},"modified":"2013-04-19T13:22:50","modified_gmt":"2013-04-19T11:22:50","slug":"epidemiak-zurrumurruak-eta-eraso-terroristak-detektatzeko-algoritmo-bat","status":"publish","type":"post","link":"https:\/\/mukom.mondragon.edu\/numbers\/2013\/04\/19\/epidemiak-zurrumurruak-eta-eraso-terroristak-detektatzeko-algoritmo-bat\/","title":{"rendered":"Epidemiak, zurrumurruak eta eraso terroristak detektatzeko algoritmo bat."},"content":{"rendered":"<p style=\"text-align: justify\">En esta ocasi\u00f3n, os acercamos una noticia sobre \u00abUn algoritmo para detectar ataques terroristas, epidemias y rumores\u00bb. Unos investigadores suizos desarrollaron este m\u00e9todo que validaron a trav\u00e9s de simulaciones de ordenador. Por ejemplo, en los ataques terroristas del 11 de septiembre, simularon todas las conversaciones telef\u00f3nicas y mensajes que hubo y su m\u00e9todo les dio los nombres de tres sospechosos. Uno de ellos, fue el autor intelectual del atentado seg\u00fan las autoridades. Tambi\u00e9n ha sido probado en epidemias como el c\u00f3lera. <a href=\"http:\/\/www.abc.es\/20120810\/medios-redes\/abci-algoritmo-rumor-epidemia-terroristas-201208101735.html\">Aqu\u00ed<\/a> ten\u00e9is la noticia completa.<\/p>\n<p style=\"text-align: justify\">Gracias a Naroa Curiel por la noticia. Puede ser interesante que seamos capaces de descubrir de quien parte un rumor que nos ha llegado, \u00bfverdad? Muchas veces funciona muy r\u00e1pido el boca a boca y la noticia llega bastante \u00abdifuminada, cambiada&#8230;\u00bb. \u00bfPara qu\u00e9 utilizar\u00edais vosotros el algoritmo?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta ocasi\u00f3n, os acercamos una noticia sobre \u00abUn algoritmo para detectar ataques terroristas, epidemias y rumores\u00bb. Unos investigadores suizos desarrollaron este m\u00e9todo que validaron a trav\u00e9s de simulaciones de ordenador. Por ejemplo, en los ataques terroristas del 11 de septiembre, simularon todas las conversaciones telef\u00f3nicas y mensajes que hubo y su m\u00e9todo les dio los nombres de tres sospechosos. Uno de ellos, fue el autor intelectual del atentado seg\u00fan las autoridades. Tambi\u00e9n ha sido probado en epidemias como el c\u00f3lera. Aqu\u00ed ten\u00e9is la noticia completa. Gracias a Naroa Curiel por la noticia. Puede ser interesante que seamos capaces de descubrir de quien parte un rumor que nos ha llegado, \u00bfverdad? Muchas veces funciona muy r\u00e1pido el boca a boca y la noticia llega bastante \u00abdifuminada, cambiada&#8230;\u00bb. \u00bfPara qu\u00e9 utilizar\u00edais vosotros el algoritmo?<\/p>\n","protected":false},"author":265,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/863"}],"collection":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/comments?post=863"}],"version-history":[{"count":0,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/863\/revisions"}],"wp:attachment":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/media?parent=863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/categories?post=863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/tags?post=863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}