{"id":928,"date":"2013-09-18T10:11:35","date_gmt":"2013-09-18T08:11:35","guid":{"rendered":"http:\/\/blog-pertsonalak.mondragon.edu\/numbers\/?p=928"},"modified":"2013-09-18T10:11:35","modified_gmt":"2013-09-18T08:11:35","slug":"kaixo-kurtso-berriari","status":"publish","type":"post","link":"https:\/\/mukom.mondragon.edu\/numbers\/2013\/09\/18\/kaixo-kurtso-berriari\/","title":{"rendered":"Kaixo kurtso berriari!!"},"content":{"rendered":"<p>Aupa denoi:<\/p>\n<p style=\"text-align: justify\">\u00bfC\u00f3mo empezamos el curso? Tenemos muchas ganas de aprender cosas, \u00bfverdad? \u00a0A trav\u00e9s de este blog intentaremos de manera divertida y curiosa ir viendo cosas de matem\u00e1ticas. Todas las semanas tendr\u00e9is diversos post; en uno de ellos tendr\u00e9is una adivinanza a la que tendr\u00e9is que encontrar respuesta y a su vez habr\u00e1 otros post sobre los cuales comentar: noticias, v\u00eddeos, im\u00e1genes, &#8230;.Cuanto m\u00e1s particip\u00e9is mejor: m\u00e1s cosas aprenderemos. Pod\u00e9is participar con cualquier informaci\u00f3n relacionada con las matem\u00e1ticas.<\/p>\n<p style=\"text-align: justify\">Ongi etorri eta ea kurtso politta edukitzen dugun!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aupa denoi: \u00bfC\u00f3mo empezamos el curso? Tenemos muchas ganas de aprender cosas, \u00bfverdad? \u00a0A trav\u00e9s de este blog intentaremos de manera divertida y curiosa ir viendo cosas de matem\u00e1ticas. Todas las semanas tendr\u00e9is diversos post; en uno de ellos tendr\u00e9is una adivinanza a la que tendr\u00e9is que encontrar respuesta y a su vez habr\u00e1 otros post sobre los cuales comentar: noticias, v\u00eddeos, im\u00e1genes, &#8230;.Cuanto m\u00e1s particip\u00e9is mejor: m\u00e1s cosas aprenderemos. Pod\u00e9is participar con cualquier informaci\u00f3n relacionada con las matem\u00e1ticas. Ongi etorri eta ea kurtso politta edukitzen dugun!<\/p>\n","protected":false},"author":265,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/928"}],"collection":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/comments?post=928"}],"version-history":[{"count":0,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/posts\/928\/revisions"}],"wp:attachment":[{"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/media?parent=928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/categories?post=928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/numbers\/wp-json\/wp\/v2\/tags?post=928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}