{"id":2,"date":"2009-04-04T09:59:00","date_gmt":"2009-04-04T09:59:00","guid":{"rendered":"http:\/\/mukom.mondragon.edu\/relacionesconclientes\/2009\/04\/04\/decisiones-2-0-el-poder-de-la-inteligencia-colectiva\/"},"modified":"2009-04-04T09:59:00","modified_gmt":"2009-04-04T09:59:00","slug":"decisiones-2-0-el-poder-de-la-inteligencia-colectiva","status":"publish","type":"post","link":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/2009\/04\/04\/decisiones-2-0-el-poder-de-la-inteligencia-colectiva\/","title":{"rendered":"Decisiones 2.0, el poder de la inteligencia colectiva"},"content":{"rendered":"<div style=\"text-align: justify\">Lanzaba la pregunta en un <a href=\"http:\/\/relacionesconclientes.blogspot.com\/2009\/03\/decisiones-20-y-inteligencia-colectiva.html\">post <\/a>anterior acerca de la inteligencia colectiva, y su uso en los procesos de  toma de decisiones. La cuesti\u00f3n ven\u00eda a cuenta del  art\u00edculo publicado en Harvard Deusto Business Review, por <a href=\"http:\/\/www.openp2p.com\/pub\/a\/p2p\/2003\/02\/21\/bonabeau.html\">Eric Bonabeau<\/a>, \u00ab<a href=\"http:\/\/www.box.net\/shared\/ym57d3ycgb\">Decisiones 2.0: El poder de la inteligencia colectiva<\/a>\u00ab.<\/p>\n<p>Conceptos como crowdsourcing (muy bueno el <a href=\"http:\/\/obea.blogs.mondragon.edu\/archives\/54\">post <\/a>de la gente de OBEA sobre el tema) parten de un apriori muy atractivo: Muchas personas participando en un problema, facilitan su resoluci\u00f3n. Pero \u00bfes esto cierto?. Considerando que toda decisi\u00f3n conlleva dos tareas b\u00e1sicas, delimitar el problema\/generar soluciones y la evaluaci\u00f3n de las alternativas, el autor se\u00f1ala que,<\/p>\n<p><span><span style=\"font-style: italic\">\u00abEntre las conclusiones destacamos, que la inteligencia colectiva ofrece mejores resultados en labores de generaci\u00f3n de respuestas que en su evaluaci\u00f3n. A pesar de sus limitaciones, un grupo de personas diferentes, independientes y razonablemente bien informadas pueden obtener mejores resultados que incluso la mejor estimaci\u00f3n o decisi\u00f3n individual\u00bb.<\/span> <\/span><\/p>\n<p>A pesar del atractivo del concepto, son diversas las dudas que plantea, como, por ejemplo:<\/p>\n<p>1. <span style=\"font-weight: bold\">Control<\/span>, existe un miedo a la perdida de control motivada por 1) logros de resultados no esperados, 2) imprevisilidad, es decir, decisiones que no siendo malas no puedan ser asumidas por al organizaci\u00f3n por no estar preparada para afrontarla y 3) la responsabilidad no asignada o dicho de otra forma \u00bfqui\u00e9n es el culpable de que hayamos fallado en la decisi\u00f3n que tomamos entre todos?.<\/p>\n<p>2. <span style=\"font-weight: bold\">Diversidad  frente a especializaci\u00f3n<\/span>: En este tipo de procesos es necesario un equilibrio entre ambos elementos. En algunos casos nos interesa enfatizar la diversidad (cuanto m\u00e1s gente  y m\u00e1s diferente, mejor) pero en todo caso las personas deber\u00e1n tener un m\u00ednimo conocimiento sobre el tema a abordar.<\/p>\n<p>3. <span style=\"font-weight: bold\">Compromiso<\/span>: Los incentivos (<a href=\"http:\/\/dsanchez.blogs.mondragon.edu\/2009\/02\/03\/crowdsourcing-e-incentivos\/\">David <\/a>habla de ello en su blog) para participar pueden ser diversos, desde incentivos econ\u00f3micos hasta los basados en el valor.<\/p>\n<p>4. <span style=\"font-weight: bold\">Vigilancia<\/span>: Dado que la probabilidad de que alguien se porte \u00abmal\u00bb se amplia con el tama\u00f1o del grupo, alg\u00fan sistema de vigilancia m\u00e1s o menos \u00absoft\u00bb es necesario.<\/p>\n<p>5. <span style=\"font-weight: bold\">Propiedad intelectual<\/span>: Cuesti\u00f3n relacionada, por un lado, con el hecho de hacer p\u00fablica una informaci\u00f3n interna para que los participantes puedan realizar aportaciones y, por otro, lcon a titularidad de las aportaciones externas a la resoluci\u00f3n del problema.<\/p>\n<p>Obviamnete el dise\u00f1o de procesos de toma de decisiones colectivas no es sencillo y requiere, entre otras, dar respuesta a preguntas como: \u00bfse deber\u00eda permitir que las aportaciones de todos los particpantes tuvieran el mismo valor?. Si no es as\u00ed, \u00bfc\u00f3mo seleccionamos a los individuos \u00abespeciales\u00bb?. \u00bfSer\u00e1 la toma de decisiones distribuida o centralizada?.<\/p>\n<p>De forma m\u00e1s espec\u00edfica y en el campo del marketing algunas de las aplicaciones de la inteligencia colectiva m\u00e1s habituales son,<\/p>\n<p>&#8211; Los <span style=\"font-style: italic\">estudios de mercado<\/span> (donde las mediciones clave son la capacidad para descubiri u obtener respuestas verdaderas y los indicadores el tama\u00f1o de la muestra, su representatividad y el compromiso de los participantes). A t\u00edtulo de ejemplo, el autor se\u00f1ala los casos de Mechanical Turt y <a href=\"http:\/\/www.affinnova.com\/\">Affinnova<\/a>.<\/p>\n<p>&#8211; <span style=\"font-style: italic\">La atenci\u00f3n al cliente<\/span> (mediciones clave, el % de problemas solucionados, tono de las conversaciones y el r\u00e1pido descubrimiento de problemas y los indicadores clave la capacidad de respuesta a los problemas planteados y el compromiso).<\/p>\n<p>En cuanto a los riesgos el autor propone como razones que explican  el porque ciertas aplicaciones de herramientas colectivas 2.0 no han funcionado el no proporcionar informaci\u00f3n sobre los participantes (lo que plantea inquietudes sobre la exactitud del resultado)  y la ausencia de procesos de arbitraje.<\/p>\n<p>Para acabar, el autor comenta:<\/p>\n<p><span style=\"font-size:85%\"><span>\u00ab&#8230;har\u00eda bien en comprender algunos aspectos fundamentales como el equilibrio entre la diversidad y la especializaci\u00f3n, y la distinci\u00f3n entre la toma de decisiones descentralizada y distribuida. Despu\u00e9s de todo, sin este tipo de conocimiento b\u00e1sico, una empresa podr\u00eda acabar f\u00e1cilmente explotando la locura de la multitud, no su sabidur\u00eda\u00bb. <\/span><\/span><\/p>\n<p>Y <span style=\"font-weight: bold\">yo me pregunto<\/span>, \u00bf. es siempre la multitud m\u00e1s sabia que un \u00fanico individuo?. Las decisiones  tomadas entre varios, \u00bfson siempre mejores que las  tomadas por un menor n\u00famero de individuos?.<\/p>\n<\/div>\n<div class=\"blogger-post-footer\"><img loading=\"lazy\" width=\"1\" height=\"1\" src=\"https:\/\/blogger.googleusercontent.com\/tracker\/9170098098482835922-2577348625318304899?l=relacionesconclientes.blogspot.com\" alt=\"\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lanzaba la pregunta en un post anterior acerca de la inteligencia colectiva, y su uso en los procesos de toma de decisiones. La cuesti\u00f3n ven\u00eda a cuenta del art\u00edculo publicado en Harvard Deusto Business Review, por Eric Bonabeau, \u00abDecisiones 2.0: El poder de la inteligencia colectiva\u00ab. Conceptos como crowdsourcing (muy bueno el post de la gente de OBEA sobre el tema) parten de un apriori muy atractivo: Muchas personas participando en un problema, facilitan su resoluci\u00f3n. Pero \u00bfes esto cierto?. Considerando que toda decisi\u00f3n conlleva dos tareas b\u00e1sicas, delimitar el problema\/generar soluciones y la evaluaci\u00f3n de las alternativas, el autor se\u00f1ala que, \u00abEntre las conclusiones destacamos, que la inteligencia colectiva ofrece mejores resultados en labores de generaci\u00f3n de respuestas que en su evaluaci\u00f3n. A pesar de sus limitaciones, un grupo de personas diferentes, independientes y razonablemente bien informadas pueden obtener..<\/p>\n","protected":false},"author":99,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[7,8,9],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/posts\/2"}],"collection":[{"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":0,"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/posts\/2\/revisions"}],"wp:attachment":[{"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/media?parent=2"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/categories?post=2"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/tags?post=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}