{"id":86,"date":"2007-11-11T05:02:00","date_gmt":"2007-11-11T05:02:00","guid":{"rendered":"http:\/\/mukom.mondragon.edu\/relacionesconclientes\/2007\/11\/11\/branding-en-entornos-btob\/"},"modified":"2007-11-11T05:02:00","modified_gmt":"2007-11-11T05:02:00","slug":"branding-en-entornos-btob","status":"publish","type":"post","link":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/2007\/11\/11\/branding-en-entornos-btob\/","title":{"rendered":"Branding en entornos btob"},"content":{"rendered":"<p>Gracias a <a href=\"http:\/\/www.yellowing.net\/blog\/\">J<\/a><a href=\"http:\/\/www.unibell.com.ar\/VentasWeb\/GE%20altab.JPG\"><img style=\"margin: 0pt 10px 10px 0pt;float: left;cursor: pointer;width: 137px;height: 152px\" src=\"http:\/\/www.unibell.com.ar\/VentasWeb\/GE%20altab.JPG\" alt=\"\" border=\"0\" \/><\/a><a href=\"http:\/\/www.yellowing.net\/blog\/\">uanjo<\/a>, uno de mis consultores favoritos, consigo un <a href=\"http:\/\/www.box.net\/shared\/eb09703q8z\">art\u00edculo <\/a>sobre \u00ab<a href=\"http:\/\/es.wikipedia.org\/wiki\/Branding\">branding<\/a>\u00bb en entornos btob, esto es, industriales. No siendo un experto en branding, el art\u00edculo me ha parecido muy interesante porque describe de forma sencilla un caso de Estrategia de branding en una empresa que opera en mercados btob (<a href=\"http:\/\/www.moog.com\/home\/\">Moog, Inc.<\/a>). Del art\u00edculo, altamente recomendable, merece la pena destacar:<\/p>\n<p>1. \u00bfCu\u00e1les son los motivos que hacen que una empresa se plantee \u00abhacer algo\u00bb con su estrategia de marca?. Varios, pero sobre todo, dos:<\/p>\n<p>&#8211; <span style=\"font-weight: bold\">Comoditizaci\u00f3n y madurez de los mercados tradicionales<\/span> y, por tanto, necesidad de buscar diferenciaci\u00f3n m\u00e1s all\u00e1 del producto f\u00edsico. Por ejemplo, mediante el servicio, creaci\u00f3n de confianza en el proveedor, alineamiento de valores o construcci\u00f3n de una relaci\u00f3n de asociados, en lugar de la tradicional proveedor-cliente.<br \/>&#8211; <span style=\"font-weight: bold\">Proceso de consolidaci\u00f3n y globalizaci\u00f3n de los clientes<\/span> y, como consecuencia, aumento de los puntos de contacto proveedor-cliente. Este proliferaci\u00f3n de puntos de contacto da lugar a m\u00falples \u00abmomentos de la verdad\u00bb, aumentando el riesgo de experiencias \u00abpoco satisfactorias\u00bb.<br \/><a href=\"http:\/\/www.revistafuturos.info\/images\/futuros_6\/mondragon_logo.gif\"><img style=\"margin: 0pt 0pt 10px 10px;float: right;cursor: pointer;width: 200px\" src=\"http:\/\/www.revistafuturos.info\/images\/futuros_6\/mondragon_logo.gif\" alt=\"\" border=\"0\" \/><\/a><br \/>2. \u00bfC\u00f3mo (re)dise\u00f1ar la estrategia de marca?. Si bien este apartado es de \u00abmanual\u00bb, con el t\u00edpico proceso de 1) auditor\u00eda o evaluaci\u00f3n, 2) definici\u00f3n de la arquitectura de marca, 3) posicionamiento y 4) implementaci\u00f3n,  la forma en que se desarroll\u00f3 en Moog es interesante.<\/p>\n<p>3. Factores de \u00e9xito\/Aspectos destacables del proceso: Hay varios pero me quedo con:<\/p>\n<p>&#8211; Los empleados son la clave del \u00e9xito, dado que son ellos los que mantienen el contacto con el cliente y, por tanto, generan experiencias m\u00e1s o menos gratificantes. Dise\u00f1ar un plan de comunicaci\u00f3n es la parte \u00abfun\u00bb del proceso, modificar percepciones, generar aceptaci\u00f3n entre quienes lo tienen que poner en marcha es la parte menos \u00abfun\u00bb.<\/p>\n<p>&#8211; En casi todos los casos (por razones de diverso tipo) habr\u00e1 personas que \u00abboicotear\u00e1n\u00bb el proceso de redefinici\u00f3n de marca. Hay que definir estrategias para involucrarlos o, en su caso, minimizar su influencia.<\/p>\n<p>&#8211; Poner a los clientes a trabajar: Incluir a los clientes en este proceso aporta conocimiento insustituible y contribuye a reducir las posibles resistencias internas.<\/p>\n<p>&#8211; Comunicar los \u00e9xitos, por peque\u00f1os que sean con frecuencia.<\/p>\n<p>Bueno, no parece muy dif\u00edcil, \u00bfno?. Y tu empresa, \u00bfnecesita redefinir su estrategia de marca?<\/p>\n<div class=\"blogger-post-footer\"><img loading=\"lazy\" width=\"1\" height=\"1\" src=\"https:\/\/blogger.googleusercontent.com\/tracker\/9170098098482835922-3287218301595062276?l=relacionesconclientes.blogspot.com\" alt=\"\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gracias a Juanjo, uno de mis consultores favoritos, consigo un art\u00edculo sobre \u00abbranding\u00bb en entornos btob, esto es, industriales. No siendo un experto en branding, el art\u00edculo me ha parecido muy interesante porque describe de forma sencilla un caso de Estrategia de branding en una empresa que opera en mercados btob (Moog, Inc.). Del art\u00edculo, altamente recomendable, merece la pena destacar: 1. \u00bfCu\u00e1les son los motivos que hacen que una empresa se plantee \u00abhacer algo\u00bb con su estrategia de marca?. Varios, pero sobre todo, dos: &#8211; Comoditizaci\u00f3n y madurez de los mercados tradicionales y, por tanto, necesidad de buscar diferenciaci\u00f3n m\u00e1s all\u00e1 del producto f\u00edsico. Por ejemplo, mediante el servicio, creaci\u00f3n de confianza en el proveedor, alineamiento de valores o construcci\u00f3n de una relaci\u00f3n de asociados, en lugar de la tradicional proveedor-cliente.&#8211; Proceso de consolidaci\u00f3n y globalizaci\u00f3n de los clientes..<\/p>\n","protected":false},"author":99,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[14,89,13],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/posts\/86"}],"collection":[{"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":0,"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/posts\/86\/revisions"}],"wp:attachment":[{"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/media?parent=86"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/categories?post=86"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mukom.mondragon.edu\/relacionesconclientes\/wp-json\/wp\/v2\/tags?post=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}